{"id":520,"date":"2014-09-29T17:01:25","date_gmt":"2014-09-29T17:01:25","guid":{"rendered":"http:\/\/valparaisoediciones.es\/noticias\/?p=520"},"modified":"2014-09-29T17:01:25","modified_gmt":"2014-09-29T17:01:25","slug":"jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos","status":"publish","type":"post","link":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/","title":{"rendered":"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos"},"content":{"rendered":"<p>Con motivo de la nominaci\u00f3n de Jugar con fuego, el disco que une poes\u00eda y flamenco en la voz de Juan Pinilla y la palabra de Fernando Valverde, Valpara\u00edso Ediciones ha emitido la siguiente nota de prensa, que pod\u00e9is leer aqu\u00ed.<br \/>\nNOTA DE PRENSA<\/p>\n<p>El disco &#8216;Jugar con fuego&#8217;, de Juan Pinilla y Fernando Valverde, nominados a los premios Grammy latinos<\/p>\n<p>El disco &#8216;Jugar con fuego&#8217;, del cantaor Juan Pinilla (1983) y el poeta Fernando Valverde (1980) , ha sido nominado como uno de los cinco finalistas a &#8216;Mejor \u00c1lbum de M\u00fasica flamenca del a\u00f1o&#8217; para la 15 edici\u00f3n de los Grammy Latinos, que se entregar\u00e1n en una gala el 20 de noviembre pr\u00f3ximo en el MGM Grand Garden Arena de Las Vegas, desde donde ser\u00e1 retransmitida en directo por la cadena Univisi\u00f3n.<\/p>\n<p>&#8216;Jugar con fuego&#8217;, editado por Valpara\u00edso Ediciones, ha sido elegido para estos premios, junto al disco &#8216;Alchemya&#8217;, de Juan Carmona, &#8216;Canci\u00f3n andaluza&#8217;, de Paco de Luc\u00eda, &#8216;Morente&#8217;, de Enrique Morente, y &#8216;Fatum&#8217;, de Rosario La Tremendita.<\/p>\n<p>Seg\u00fan explica el propio presidente de La Academia Latina de la Grabaci\u00f3n, Gabriel Abaroa, en la web de los Latin Grammy (http:\/\/www.latingrammy.com), para el 15 aniversario de los galardones se recibieron \u201cm\u00e1s de 10.000 grabaciones\u201d, que son revisadas por grupos de expertos en las distintas categor\u00edas y que en la fase final de la selecci\u00f3n son designadas por comit\u00e9s nacionales conformados por miembros votantes de la Academia tanto de los Estados Unidos como de Latinoam\u00e9rica.<\/p>\n<p>Tras conocer la noticia, Pinilla ha dicho sentirse \u201cabsolutamente abrumado\u201d, m\u00e1xime cuando &#8216;Jugar con fuego&#8217; \u201cse encuentra al lado de figuras como la del gran Paco de Luc\u00eda o el maestro Enrique Morente\u201d. Adem\u00e1s, ha querido destacar la presencia del flamenco en los Grammys y \u201cc\u00f3mo poco a poco nuestra m\u00fasica se ha ido abriendo hueco en los premios m\u00e1s medi\u00e1ticos de la m\u00fasica latina\u201d.<\/p>\n<p>\u201cPara m\u00ed es algo que no esperaba en absoluto, que me coge por completo de sorpresa, pero que supone una ilusi\u00f3n tremenda por el cari\u00f1o que le pusimos a Jugar con Fuego\u201d, se\u00f1ala el cantaor, que considera que el mero hecho de la nominaci\u00f3n es ya para \u00e9l \u201cun gran reconocimiento\u201d. \u201cS\u00f3lo puedo expresar mi enorme alegr\u00eda y compartirla con mis compa\u00f1eros de proyecto\u201d, ha indicado.<\/p>\n<p>Valverde, que puso letra a las canciones del \u00e1lbum, coincide con Pinilla en que la nominaci\u00f3n ha sido \u201cuna sorpresa enorme\u201d: \u201cUno no puede imaginar tener tanta suerte al lado de Paco de Luc\u00eda o Enrique Morente\u201d. El poeta cree que esta nominaci\u00f3n es algo merecido sobre todo para el trabajo de Juan Pinilla, que \u201ctiene un gran talento que la mayor\u00eda de la gente no ha visto\u201d. \u201cTiene una voz y una sensibilidad para transmitir emociones que pocas veces he visto en un int\u00e9rprete\u201d, ha dicho.<\/p>\n<p>El director de Valpara\u00edso Ediciones, Javier Bozalongo, tambi\u00e9n ha mostrado su alegr\u00eda por la nominaci\u00f3n de un disco que re\u00fane poes\u00eda y flamenco y que adem\u00e1s es el primero de la colecci\u00f3n de m\u00fasica de la editorial. \u201cJugar con fuego re\u00fane al mejor poeta de su generaci\u00f3n con una voz privilegiada del nuevo flamenco\u201d, ha mantenido.<\/p>\n<p>El disco-libro, que se termin\u00f3 de grabar el 4 de diciembre del pasado a\u00f1o en los Estudios de FJR de Granada, cont\u00f3 con la producci\u00f3n de Enrique Bjeta, y recopila algunos de los mejores poemas de Valverde que han sido adaptados por su autor para la m\u00fasica compuesta por Juan Pinilla, que los interpreta junto al guitarrista David Caro.<\/p>\n<p>Se trata de un trabajo de fusi\u00f3n entre la poes\u00eda y el flamenco que se gest\u00f3 hace a\u00f1os durante un viaje a Italia, y que incluye un total de 12 poemas, entre ellos &#8216;Celia&#8217;, ganador del Premio Antonio Machado, y otros de libros anteriores de Valverde, como &#8216;La ca\u00edda&#8217;, &#8216;La apariencia&#8217; o &#8216;El lago&#8217;, algunos de los cuales son recitados en el disco por el autor. Adem\u00e1s, varias de las canciones del \u00e1lbum fueron escritas espec\u00edficamente para este trabajo, como es el caso de &#8216;Revoluci\u00f3n&#8217;, un poema que tiene como fondo la actual situaci\u00f3n social de Espa\u00f1a y la \u00abapat\u00eda\u00bb de muchas personas ante las \u201cinjusticias y los abusos de poder\u201d.<\/p>\n<p>&#8216;Jugar con fuego&#8217;, que cuenta adem\u00e1s con la colaboraci\u00f3n de Agust\u00edn Puertas, al bajo, Josu\u00e9 Heredia &#8216;Che\u00edto&#8217;, en percusiones, y de Fernando Romero, en las mezclas, se ha convertido tambi\u00e9n en un espect\u00e1culo de flamenco y poes\u00eda que se llevar\u00e1 a escenarios de M\u00e9xico y Centroam\u00e9rica en pr\u00f3ximas fechas.<br \/>\nJuan Pinilla (Hu\u00e9tor T\u00e1jar, 1983) obtuvo en 2007 la L\u00e1mpara Minera, considerado el galard\u00f3n flamenco m\u00e1s importante en la actualidad. Su \u00faltimo trabajo es &#8216;Las voces que no callaron&#8217; (Atrapasue\u00f1os), en el que se adentra en el cante de los flamencos que lucharon por la libertad durante la dictadura franquista. Est\u00e1 considerado como una de las m\u00e1ximas figuras del flamenco en su generaci\u00f3n.<br \/>\nFernando Valverde (Granada, 1980) se ha convertido en una de las voces de la poes\u00eda espa\u00f1ola con m\u00e1s proyecci\u00f3n internacional. Sus poemas se han publicado en Argentina, M\u00e9xico, Colombia, Per\u00fa, Chile, Nicaragua, El Salvador, Estados Unidos, Bolivia, Ecuador o Italia, entre otros pa\u00edses, y han sido traducidos a numerosos idiomas. Ha obtenido importantes premios como el Antonio Machado o el Emilio Alarcos del Principado de Asturias. Actualmente, ejerce de profesor de Literatura espa\u00f1ola en la University of North Georgia, en Estados Unidos.<br \/>\nTres de sus libros, &#8216;Razones para huir de una ciudad con fr\u00edo&#8217;, &#8216;Los ojos del pel\u00edcano&#8217;, y su \u00faltimo trabajo, &#8216;La insistencia del da\u00f1o&#8217;, que se encuentra entre los libros de poes\u00eda m\u00e1s vendidos del pa\u00eds, est\u00e1n publicados en la prestigiosa editorial Visor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de la nominaci\u00f3n de Jugar con fuego, el disco que une poes\u00eda y flamenco en la voz de Juan Pinilla y la palabra de Fernando Valverde, Valpara\u00edso Ediciones ha emitido la siguiente nota de prensa, que pod\u00e9is leer aqu\u00ed. NOTA DE PRENSA El disco &#8216;Jugar con fuego&#8217;, de Juan Pinilla y Fernando Valverde, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abJugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,86],"tags":[149,148,147,106,121,55],"class_list":["post-520","post","type-post","status-publish","format-standard","hentry","category-noticias","category-prensa","tag-comunicado","tag-fuego","tag-jugar","tag-pinilla","tag-prensa-2","tag-valverde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos - Valparaiso Ediciones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos - Valparaiso Ediciones\" \/>\n<meta property=\"og:description\" content=\"Con motivo de la nominaci\u00f3n de Jugar con fuego, el disco que une poes\u00eda y flamenco en la voz de Juan Pinilla y la palabra de Fernando Valverde, Valpara\u00edso Ediciones ha emitido la siguiente nota de prensa, que pod\u00e9is leer aqu\u00ed. NOTA DE PRENSA El disco &#8216;Jugar con fuego&#8217;, de Juan Pinilla y Fernando Valverde, &hellip; Continuar leyendo &quot;Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\" \/>\n<meta property=\"og:site_name\" content=\"Valparaiso Ediciones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/valparaiso.ediciones\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-29T17:01:25+00:00\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ValparaisoEd\" \/>\n<meta name=\"twitter:site\" content=\"@ValparaisoEd\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\"},\"author\":{\"name\":\"Administrador\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/person\/a23eb8fd06a3539c8ffe2230e32817f1\"},\"headline\":\"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos\",\"datePublished\":\"2014-09-29T17:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\"},\"wordCount\":1024,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#organization\"},\"keywords\":[\"comunicado\",\"fuego\",\"jugar\",\"pinilla\",\"prensa\",\"valverde\"],\"articleSection\":[\"Noticias\",\"Prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\",\"url\":\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\",\"name\":\"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos - Valparaiso Ediciones\",\"isPartOf\":{\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#website\"},\"datePublished\":\"2014-09-29T17:01:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/valparaisoediciones.es\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#website\",\"url\":\"https:\/\/valparaisoediciones.es\/noticias\/\",\"name\":\"Valparaiso Ediciones\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/valparaisoediciones.es\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#organization\",\"name\":\"Valpara\u00edso Ediciones\",\"url\":\"https:\/\/valparaisoediciones.es\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/valparaisoediciones.es\/noticias\/wp-content\/uploads\/2012\/12\/logo.png\",\"contentUrl\":\"http:\/\/valparaisoediciones.es\/noticias\/wp-content\/uploads\/2012\/12\/logo.png\",\"width\":320,\"height\":121,\"caption\":\"Valpara\u00edso Ediciones\"},\"image\":{\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/valparaiso.ediciones\",\"https:\/\/x.com\/ValparaisoEd\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/person\/a23eb8fd06a3539c8ffe2230e32817f1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7bca4ba132c9cf6584007b282c38c7c3c01797d94c033ae2f6efa9a85b829dcd?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7bca4ba132c9cf6584007b282c38c7c3c01797d94c033ae2f6efa9a85b829dcd?s=96&d=blank&r=g\",\"caption\":\"Administrador\"},\"sameAs\":[\"http:\/\/valparaisoediciones.es\"],\"url\":\"https:\/\/valparaisoediciones.es\/noticias\/author\/administrador\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos - Valparaiso Ediciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/","og_locale":"es_ES","og_type":"article","og_title":"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos - Valparaiso Ediciones","og_description":"Con motivo de la nominaci\u00f3n de Jugar con fuego, el disco que une poes\u00eda y flamenco en la voz de Juan Pinilla y la palabra de Fernando Valverde, Valpara\u00edso Ediciones ha emitido la siguiente nota de prensa, que pod\u00e9is leer aqu\u00ed. NOTA DE PRENSA El disco &#8216;Jugar con fuego&#8217;, de Juan Pinilla y Fernando Valverde, &hellip; Continuar leyendo \"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos\"","og_url":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/","og_site_name":"Valparaiso Ediciones","article_publisher":"https:\/\/www.facebook.com\/valparaiso.ediciones","article_published_time":"2014-09-29T17:01:25+00:00","author":"Administrador","twitter_card":"summary_large_image","twitter_creator":"@ValparaisoEd","twitter_site":"@ValparaisoEd","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#article","isPartOf":{"@id":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/"},"author":{"name":"Administrador","@id":"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/person\/a23eb8fd06a3539c8ffe2230e32817f1"},"headline":"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos","datePublished":"2014-09-29T17:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/"},"wordCount":1024,"commentCount":0,"publisher":{"@id":"https:\/\/valparaisoediciones.es\/noticias\/#organization"},"keywords":["comunicado","fuego","jugar","pinilla","prensa","valverde"],"articleSection":["Noticias","Prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/","url":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/","name":"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos - Valparaiso Ediciones","isPartOf":{"@id":"https:\/\/valparaisoediciones.es\/noticias\/#website"},"datePublished":"2014-09-29T17:01:25+00:00","breadcrumb":{"@id":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/valparaisoediciones.es\/noticias\/2014\/09\/jugar-con-fuego-de-pinilla-y-valverde-candidato-a-los-grammy-latinos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valparaisoediciones.es\/noticias\/"},{"@type":"ListItem","position":2,"name":"Jugar con fuego, de Pinilla y Valverde, candidato a los Grammy Latinos"}]},{"@type":"WebSite","@id":"https:\/\/valparaisoediciones.es\/noticias\/#website","url":"https:\/\/valparaisoediciones.es\/noticias\/","name":"Valparaiso Ediciones","description":"Noticias","publisher":{"@id":"https:\/\/valparaisoediciones.es\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valparaisoediciones.es\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/valparaisoediciones.es\/noticias\/#organization","name":"Valpara\u00edso Ediciones","url":"https:\/\/valparaisoediciones.es\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/logo\/image\/","url":"http:\/\/valparaisoediciones.es\/noticias\/wp-content\/uploads\/2012\/12\/logo.png","contentUrl":"http:\/\/valparaisoediciones.es\/noticias\/wp-content\/uploads\/2012\/12\/logo.png","width":320,"height":121,"caption":"Valpara\u00edso Ediciones"},"image":{"@id":"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valparaiso.ediciones","https:\/\/x.com\/ValparaisoEd"]},{"@type":"Person","@id":"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/person\/a23eb8fd06a3539c8ffe2230e32817f1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valparaisoediciones.es\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7bca4ba132c9cf6584007b282c38c7c3c01797d94c033ae2f6efa9a85b829dcd?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7bca4ba132c9cf6584007b282c38c7c3c01797d94c033ae2f6efa9a85b829dcd?s=96&d=blank&r=g","caption":"Administrador"},"sameAs":["http:\/\/valparaisoediciones.es"],"url":"https:\/\/valparaisoediciones.es\/noticias\/author\/administrador\/"}]}},"_links":{"self":[{"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/posts\/520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":1,"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/posts\/520\/revisions"}],"predecessor-version":[{"id":521,"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/posts\/520\/revisions\/521"}],"wp:attachment":[{"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/media?parent=520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/categories?post=520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valparaisoediciones.es\/noticias\/wp-json\/wp\/v2\/tags?post=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}